{"id":791,"date":"2019-04-19T15:07:53","date_gmt":"2019-04-19T19:07:53","guid":{"rendered":"https:\/\/healthyhomecenter.ca\/?p=791"},"modified":"2020-11-27T14:03:25","modified_gmt":"2020-11-27T19:03:25","slug":"comment-savoir-sil-y-a-des-moisissures-dans-lentretoit","status":"publish","type":"post","link":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/","title":{"rendered":"Comment savoir s\u2019il y a des moisissures dans l\u2019entretoit?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:0px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\"><p>Avez-vous commenc\u00e9 \u00e0 \u00e9ternuer et \u00e0 tousser et vous n\u2019avez pas le rhume? Avez-vous remarqu\u00e9 une odeur de moisi provenant des \u00e9vents ou d\u2019un endroit particulier dans la maison? Il peut s\u2019agir de signes d\u2019accumulation de moisissures dans la maison ou l\u2019entretoit. Dans ces cas, les spores de moisissures peuvent facilement se disperser dans la maison par le syst\u00e8me de ventilation et ainsi d\u00e9clencher une multitude de probl\u00e8mes de sant\u00e9. Alors, si vous \u00e9prouvez des sympt\u00f4mes semblables et que vous pensez qu\u2019il y a des moisissures dans l\u2019entretoit, il est important de d\u00e9terminer leur emplacement et de les enlever le plus rapidement possible.<\/p>\n<p>Dans cet article, nous vous montrerons comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.<\/p>\n<h3>Taches noires ou blanches<\/h3>\n<p>Il n\u2019est pas toujours facile de d\u00e9tecter les moisissures, mais parfois leur pr\u00e9sence est flagrante. Si vous voyez des taches blanches et noires qui se forment sur la toiture, le bois, les solives et les cloisons s\u00e8ches, il s\u2019agit probablement de moisissures.<\/p>\n<h3>Clous rouill\u00e9s<\/h3>\n<p>La croissance de moisissures dans l\u2019entretoit est entra\u00een\u00e9e par une humidit\u00e9 excessive. Vous pouvez facilement rep\u00e9rer un probl\u00e8me d\u2019humidit\u00e9 en observant les clous dans l\u2019entretoit. Si les clous comportent des taches de rouille, c\u2019est un signe qu\u2019il y a un probl\u00e8me d\u2019humidit\u00e9 \u00e0 r\u00e9gler.<\/p>\n<h3>Accumulation d\u2019eau<\/h3>\n<p>Vous ne savez pas o\u00f9 les moisissures peuvent se dissimuler? Rep\u00e9rez les endroits o\u00f9 il pourrait y avoir une condensation excessive et une accumulation d\u2019eau et ensuite les v\u00e9rifier. Les bardeaux qui ne sont pas bien assujettis ou qui sont bris\u00e9s ou les endroits qui sont d\u00e9t\u00e9rior\u00e9s et les petits trous peuvent entra\u00eener l\u2019infiltration d\u2019une humidit\u00e9 excessive dans la maison et provoquer la croissance de moisissures.<\/p>\n<h3>\u00c9vents bouch\u00e9s<\/h3>\n<p>Il faut aussi v\u00e9rifier les \u00e9vents sur la toiture et s\u2019assurer qu\u2019ils font circuler une quantit\u00e9 d\u2019air suffisante dans l\u2019entretoit afin de contr\u00f4ler l\u2019humidit\u00e9. Si les \u00e9vents sont bouch\u00e9s, le d\u00e9bit d\u2019air sera bloqu\u00e9, l\u2019entretoit sera humide et il y aura de la condensation \u2013 la recette parfaite pour la croissance des moisissures.<\/p>\n<h3>Isolant en mauvais \u00e9tat<\/h3>\n<p>L\u2019isolant pourrait \u00e9galement vous donner une certaine indication de la pr\u00e9sence de moisissures dans l\u2019entretoit. Lorsqu\u2019il y a trop d\u2019humidit\u00e9, l\u2019isolant commence \u00e0 se d\u00e9grader. M\u00eame si vous ne voyez pas de moisissures, la pr\u00e9sence d\u2019isolant humide et gondol\u00e9 est un signe avant-coureur qu\u2019il pourrait y avoir des moisissures.<\/p>\n<h3>Fuites d\u2019air<\/h3>\n<p>Il peut aussi y avoir des moisissures autour des d\u00e9rivations qui ne sont pas scell\u00e9es dans l\u2019entretoit. Il est alors important de v\u00e9rifier les endroits o\u00f9 les fils et les c\u00e2bles p\u00e9n\u00e8trent dans l\u2019entretoit ainsi que les surfaces autour de la plomberie et des \u00e9vents de l\u2019appareil de chauffage. S\u2019il y a de la condensation, ces endroits devraient \u00eatre bien scell\u00e9s pour \u00e9viter les fuites d\u2019air dans l\u2019entretoit. Si vous ne savez pas o\u00f9 se trouvent toutes les d\u00e9rivations dans l\u2019entretoit, vous pouvez avoir recours aux services d\u2019un expert sp\u00e9cialement form\u00e9 qui pourra les rep\u00e9rer \u00e0 l\u2019aide d\u2019une cam\u00e9ra \u00e0 infrarouges.<\/p>\n<h3>Que devez-vous faire?<\/h3>\n<p>Si vous d\u00e9couvrez un des signes signifiant la croissance de moisissures dans votre maison, il est important que vous fassiez appel \u00e0 un expert pour proc\u00e9der \u00e0 l\u2019inspection, l\u2019analyse et l\u2019enl\u00e8vement des moisissures. Entretemps, vous pouvez ass\u00e9cher l\u2019entretoit ou le sous-sol \u00e0 l\u2019aide d\u2019un ventilateur pour \u00e9viter que les moisissures continuent de se former. Rappelez-vous qu\u2019il est mieux de s\u2019attaquer au probl\u00e8me le plus t\u00f4t possible. Les taches de moisissures, qu\u2019elles soient noires ou blanches, nuisent \u00e0 la qualit\u00e9 de l\u2019air et peuvent entra\u00eener de graves d\u00e9tresses respiratoires au fil du temps.<\/p>\n<p><span style=\"font-weight: 400;\">Si vous croyez qu\u2019il y a des moisissures dans votre maison, vous devriez d\u2019abord nous joindre au Healthy Home Centre \u2013 les sp\u00e9cialistes de l\u2019enl\u00e8vement des moisissures \u00e0 Ottawa.\u00a0 Healthy Home Centre prendra les mesures n\u00e9cessaires pour enlever les moisissures et redonner \u00e0 vous et votre famille un environnement sain. Nous pouvons enlever les moisissures, l\u2019amiante, les d\u00e9chets animaux et les particules ultrafines, proc\u00e9der au nettoyage des conduits ainsi que finir votre sous-sol ou se charger de la r\u00e9fection des lieux.\u00a0 Veuillez <\/span><a href=\"https:\/\/healthyhomecenter.ca\/fr\/nous-joindre\/\"><b>nous<\/b><b> joindre<\/b><\/a><span style=\"font-weight: 400;\"> aujourd\u2019hui pour conna\u00eetre les services que nous offrons et savoir comment nous pouvons vous aider \u00e0 am\u00e9liorer votre qualit\u00e9 de l\u2019air int\u00e9rieur.<\/span><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":793,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[37],"tags":[],"class_list":["post-791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/\" \/>\n<meta property=\"og:site_name\" content=\"Healthy Home Center\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Healthy-Home-Center-1683768605283953\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-19T19:07:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-27T19:03:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/\"},\"author\":{\"name\":\"Marie\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#\\\/schema\\\/person\\\/fd3b545d5b404983fa006ce22ce9e20a\"},\"headline\":\"Comment savoir s\u2019il y a des moisissures dans l\u2019entretoit?\",\"datePublished\":\"2019-04-19T19:07:53+00:00\",\"dateModified\":\"2020-11-27T19:03:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/\"},\"wordCount\":999,\"publisher\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthyhomecenter.ca\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mold-in-attic.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/\",\"url\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/\",\"name\":\"Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthyhomecenter.ca\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mold-in-attic.jpg\",\"datePublished\":\"2019-04-19T19:07:53+00:00\",\"dateModified\":\"2020-11-27T19:03:25+00:00\",\"description\":\"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthyhomecenter.ca\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mold-in-attic.jpg\",\"contentUrl\":\"https:\\\/\\\/healthyhomecenter.ca\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/mold-in-attic.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/blog\\\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"D\u2019ACCUEIL\",\"item\":\"https:\\\/\\\/healthyhomecenter.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment savoir s\u2019il y a des moisissures dans l\u2019entretoit?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#website\",\"url\":\"https:\\\/\\\/healthyhomecenter.ca\\\/\",\"name\":\"Healthy Home Center\",\"description\":\"Mold Removal Services in Ottawa\",\"publisher\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/healthyhomecenter.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#organization\",\"name\":\"Healthy Home Center\",\"url\":\"https:\\\/\\\/healthyhomecenter.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/healthyhomecen.wpengine.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/hhg-ico.png\",\"contentUrl\":\"https:\\\/\\\/healthyhomecen.wpengine.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/hhg-ico.png\",\"width\":340,\"height\":357,\"caption\":\"Healthy Home Center\"},\"image\":{\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Healthy-Home-Center-1683768605283953\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/healthyhomecenter.ca\\\/#\\\/schema\\\/person\\\/fd3b545d5b404983fa006ce22ce9e20a\",\"name\":\"Marie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g\",\"caption\":\"Marie\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center","description":"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/","og_locale":"fr_FR","og_type":"article","og_title":"Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center","og_description":"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.","og_url":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/","og_site_name":"Healthy Home Center","article_publisher":"https:\/\/www.facebook.com\/Healthy-Home-Center-1683768605283953\/","article_published_time":"2019-04-19T19:07:53+00:00","article_modified_time":"2020-11-27T19:03:25+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg","type":"image\/jpeg"}],"author":"Marie","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marie","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#article","isPartOf":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/"},"author":{"name":"Marie","@id":"https:\/\/healthyhomecenter.ca\/#\/schema\/person\/fd3b545d5b404983fa006ce22ce9e20a"},"headline":"Comment savoir s\u2019il y a des moisissures dans l\u2019entretoit?","datePublished":"2019-04-19T19:07:53+00:00","dateModified":"2020-11-27T19:03:25+00:00","mainEntityOfPage":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/"},"wordCount":999,"publisher":{"@id":"https:\/\/healthyhomecenter.ca\/#organization"},"image":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#primaryimage"},"thumbnailUrl":"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/","url":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/","name":"Savoir s\u2019il y a des moisissures dans l\u2019entretoit - Healthy Home Center","isPartOf":{"@id":"https:\/\/healthyhomecenter.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#primaryimage"},"image":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#primaryimage"},"thumbnailUrl":"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg","datePublished":"2019-04-19T19:07:53+00:00","dateModified":"2020-11-27T19:03:25+00:00","description":"D\u00e9couvrez comment rep\u00e9rer les signes de moisissures et comment se d\u00e9barrasser des moisissures pour que l\u2019environnement dans votre maison soit sain.","breadcrumb":{"@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#primaryimage","url":"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg","contentUrl":"https:\/\/healthyhomecenter.ca\/wp-content\/uploads\/2019\/05\/mold-in-attic.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/healthyhomecenter.ca\/fr\/blog\/comment-savoir-sil-y-a-des-moisissures-dans-lentretoit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"D\u2019ACCUEIL","item":"https:\/\/healthyhomecenter.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment savoir s\u2019il y a des moisissures dans l\u2019entretoit?"}]},{"@type":"WebSite","@id":"https:\/\/healthyhomecenter.ca\/#website","url":"https:\/\/healthyhomecenter.ca\/","name":"Healthy Home Center","description":"Mold Removal Services in Ottawa","publisher":{"@id":"https:\/\/healthyhomecenter.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/healthyhomecenter.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/healthyhomecenter.ca\/#organization","name":"Healthy Home Center","url":"https:\/\/healthyhomecenter.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/healthyhomecenter.ca\/#\/schema\/logo\/image\/","url":"https:\/\/healthyhomecen.wpengine.com\/wp-content\/uploads\/2018\/02\/hhg-ico.png","contentUrl":"https:\/\/healthyhomecen.wpengine.com\/wp-content\/uploads\/2018\/02\/hhg-ico.png","width":340,"height":357,"caption":"Healthy Home Center"},"image":{"@id":"https:\/\/healthyhomecenter.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Healthy-Home-Center-1683768605283953\/"]},{"@type":"Person","@id":"https:\/\/healthyhomecenter.ca\/#\/schema\/person\/fd3b545d5b404983fa006ce22ce9e20a","name":"Marie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/045525a802b036ffaae6007aaf49cb9dbd5b18838f443c2c4a3c9dd3f0859cbb?s=96&d=mm&r=g","caption":"Marie"}}]}},"_links":{"self":[{"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/posts\/791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/comments?post=791"}],"version-history":[{"count":0,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/posts\/791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/media\/793"}],"wp:attachment":[{"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/media?parent=791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/categories?post=791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/healthyhomecenter.ca\/fr\/wp-json\/wp\/v2\/tags?post=791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}